{"id":129608,"date":"2025-05-26T10:17:40","date_gmt":"2025-05-26T09:17:40","guid":{"rendered":"https:\/\/www.maxqda.com\/de\/blogpost\/"},"modified":"2025-05-28T11:55:25","modified_gmt":"2025-05-28T10:55:25","slug":"favorite-features-wort-explorer","status":"publish","type":"post","link":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer","title":{"rendered":"Favorite Features: Wort-Explorer"},"content":{"rendered":"<h2>Xans Forschungsreise mit dem MAXQDA Wort Explorer<\/h2>\r\n<p><br \/>\r\nSeien wir mal ehrlich: Qualitative Forschung kann ganz sch\u00f6n brutal sein. Ich habe gerade letzten Monat meine Masterarbeit abgegeben, und ganz ehrlich? Ich hab mich immer noch nicht ganz von dieser intensiven T\u00e4tigkeit erholt. Da hilft es, sich auf die positiven Erfahrungen zu besinnen. Eine davon war die Arbeit mit MAXQDA, besonders mit der Funktion Wort Explorer, der mir dabei geholfen hat, Struktur, Klarheit und analytischen Schwung zu finden, w\u00e4hrend ich drohte, tief in einem Chaos aus emotional aufgeladenen qualitativen Daten zu versinken.<\/p>\r\n<h2>Stop! Was bitte <em>ist<\/em> der Wort Explorer?<\/h2>\r\n<p>Um wirklich zu verstehen, wie mir diese Funktion dabei geholfen hat, meine Analyse zu knacken, sollte ich kurz erkl\u00e4ren, was der Wort-Explorer eigentlich macht.<\/p>\r\n<p>Der Wort Explorer ist ein MAXQDA Tool, mit dem man in seinem gesamten MAXQDA Projekt nach beliebigen W\u00f6rtern oder Phrasen suchen kann, zum Beispiel in Interviewtranskripten, Memos, Paraphrasen, Codierungskommentaren und Zusammenfassungen. Dabei ist das Toll viel mehr als nur eine Suchleiste: der Wort Explorer visualisiert die H\u00e4ufigkeit, Verteilung und mehrfache Auftreten von Begriffen in einem Datensatz.<\/p>\r\n<p>So konnte ich immer wiederkehrende Ausdr\u00fccke erkennen und verstehen, wo und wie sie wichtig wurden.<\/p>\r\n<p>Der Screenshot oben zeigt das Beispielprojekt \u201eWork-Life Balance\u201c von MAXQDA und wie eine Suche nach dem Begriff \u201ework\u201c im Wort Explorer aussieht. Selbst in einem Demo-Datensatz findet das Tool \u00fcberraschend n\u00fctzliche Muster: Das Wort kommt in jedem Dokument vor, hat starke Verbindungen zu Codes wie \u201epositive\u201c und \u201eworking hours\u201c und taucht oft in Ausdr\u00fccken wie \u201aArbeitszeit\u2018 und \u201etypischer Arbeitstag\u201c auf. Dies ist ein gutes Beispiel daf\u00fcr, wie viele kontextbezogene Erkenntnisse der Wort Explorer liefert.<\/p>\r\n<p>Im Grunde genommen hat das Tool das getan, was mein spiralf\u00f6rmiges Codesystem nicht konnte: Es hat mir gezeigt, was wirklich wichtig war, und nicht nur, was am lautesten schrie. Wer den Wort Explorer noch nicht verwendet oder bisher nur einen fl\u00fcchtigen Blick darauf geworfen hat, sollte unbedingt noch einen zweiten oder dritten Blick riskieren, Glauben Sie mir, es wird sich lohnen.<\/p>\r\n<p style=\"text-align: left;\">Testen Sie das Wort Explorer Tool unbedingt bei der n\u00e4chsten Analyse. Eine detaillierte \u00dcbersicht \u00fcber diese Funktion finden sich auch im <a href=\"https:\/\/www.maxqda.com\/de\/hilfe\/willkommen\">MAXQDA Manual<\/a>.<\/p>\r\n<h2>\u00dcberw\u00e4ltigt von emotionsgeladenen Daten<\/h2>\r\n<p>In meiner Masterarbeit habe ich mich mit Aktivisten besch\u00e4ftigt, die in Deutschland riskante und emotionale politische Arbeit machen. Diese Leute sind oft am Rand der \u00f6ffentlichen Debatte unterwegs, super sichtbar, wenn ihre Pr\u00e4senz einen symbolischen Zweck erf\u00fcllt, aber schnell an den Rand gedr\u00e4ngt oder diszipliniert, wenn ihre Meinung unbequem wird.<\/p>\r\n<p>Wegen der Sensibilit\u00e4t des Themas und der realen Risiken, denen die Beteiligten ausgesetzt sind, werde ich in diesem Beitrag bewusst vage bleiben, was bestimmte Aspekte meines Projekts angeht. Diese Unklarheit ist kein Vers\u00e4umnis, sondern Teil meiner Bem\u00fchungen, sowohl ihre Sicherheit als auch die ethischen Grunds\u00e4tze der Forschungsvertraulichkeit zu wahren.<\/p>\r\n<p>Insgesamt habe ich 13 ausf\u00fchrliche, halbstrukturierte Interviews gef\u00fchrt. Das Ergebnis war eine Datenmenge, die nicht nur intellektuell komplex, sondern auch emotional \u00fcberw\u00e4ltigend war.<\/p>\r\n<p>Die Transkripte waren durchzogen von Momenten des Schmerzes, der Entt\u00e4uschung, des Widerstands und gelegentlich auch von schwarzem Humor. Viele Erz\u00e4hlungen widersprachen vorherrschenden Vorstellungen von Legitimit\u00e4t, Identit\u00e4t und Zugeh\u00f6rigkeit. Was ich zun\u00e4chst als \u201eherausfordernd, aber machbar\u201c eingesch\u00e4tzt hatte, entpuppte sich schnell als ein wirres Archiv voller Widerspr\u00fcche und emotionaler Belastungen.<\/p>\r\n<p>Oft starrte ich auf meinen Bildschirm und versuchte, die wiederkehrenden Diskrepanzen zu verstehen, die die Teilnehmenden zum Ausdruck brachten: das Gef\u00fchl, in gegens\u00e4tzliche Richtungen gezogen zu werden, Systeme zu durchschauen, aber dennoch an sie gebunden zu sein. Wie konnte ich diesen Berichten gerecht werden, ohne sie in Kategorien zu pressen oder ihnen ihre Sch\u00e4rfe zu nehmen?<\/p>\r\n<h3>Wenn sich alles gleich wichtig anf\u00fchlt<\/h3>\r\n<p>Meine gr\u00f6\u00dfte Herausforderung bei der Arbeit an meiner Forschung \u2013 und wahrscheinlich auch im Leben allgemein \u2013 war, dass ich das Gef\u00fchl hatte, ALLES einbeziehen zu m\u00fcssen. Ich meine, wie k\u00f6nnte ich meine Teilnehmer und ihre Erz\u00e4hlungen \u201ew\u00fcrdigen\u201c, wenn ich nicht ALLES einbeziehe?<\/p>\r\n<p>Ja, ich wusste nat\u00fcrlich, dass ich durch das Einbeziehen von allem nur an Tiefe zugunsten von Breite einb\u00fc\u00dfen w\u00fcrde, was zu einem weitl\u00e4ufigen, unkonzentrierten Ergebnisabschnitt f\u00fchren w\u00fcrde.<\/p>\r\n<p>Aber Logik spielte keine Rolle, denn wie h\u00e4tte ich nicht jede einzelne \u00c4u\u00dferung jedes einzelnen Teilnehmers auf Satzebene analysieren k\u00f6nnen?<\/p>\r\n<p>Spoiler: Ich habe es versucht. Es hat nicht funktioniert.<\/p>\r\n<h4>Zu viele Codes, zu wenig Klarheit<\/h4>\r\n<p>Ich war zwar nicht neu in der Forschung, aber das war mein erstes richtiges qualitatives Projekt seit Jahren. Innerhalb einer Woche nach Beginn der Analyse war mein Codesystem wie ein zu prall gef\u00fcllter Wasserballon explodiert.<\/p>\r\n<p>Jeder Absatz in meinen Transkripten schien drei verschiedene Konzepte, f\u00fcnf emotionale Untert\u00f6ne und mindestens eine Zeile zu enthalten, die eine eigene theoretische Abhandlung verdient h\u00e4tte. Ich habe alles codiert. Und das hat alles nur noch schlimmer gemacht.<\/p>\r\n<p>Sogar die analytischen Gruppierungen, von denen ich dachte, dass sie funktionieren w\u00fcrden (wie die Unterscheidung zwischen Aktivisten an vorderster Front und Mitwirkenden hinter den Kulissen), hielten nicht stand. Die Rollen der Menschen verschwammen. Ebenso die Themen. Ich scrollte durch mein Codesystem und dachte: \u201eIst das noch eine Analyse oder habe ich versehentlich angefangen, einen Roman mit Fu\u00dfnoten zu schreiben?\u201c<\/p>\r\n<h2>Wenn ein Scherz zur Methode wird<\/h2>\r\n<p>So kam der Wort Explorer ins Spiel: Ich habe mich bei einem Freund ausgeweint. Ich erinnere mich, dass ich so etwas sagte wie: &#8222;Alle sagen st\u00e4ndig &#8218;das ist crazy oder &#8218;was f\u00fcr eine Sch***e.&#8216; Irgendwie ist das lustig.&#8220;<\/p>\r\n<p>Der Freund \u2013 und daf\u00fcr danke ich ihm \u2013 sagte: &#8222;Ist das nicht irgendwie &#8230; n\u00fctzlich?&#8220;<\/p>\r\n<p>Lieber Leser, das war es!<\/p>\r\n<p>Ich hatte den Wort Explorer schon einmal ge\u00f6ffnet, aber ihn nie wirklich <em>verstanden<\/em>. An diesem Tag tippte ich einfach mal &#8222;verr\u00fcckt&#8220; und &#8222;was f\u00fcr eine Sch***e&#8220; ein, nur um zu sehen, was passiert. Was passierte? Ein Durchbruch.<\/p>\r\n<p>Um zu zeigen, was ich meine, hier ein Beispiel dessen, was der Wort Explorer anzeigte, als ich nach dem Begriff &#8222;crazy&#8220; in meinem Projekt suchte:<\/p>\r\n<div class=\"large-9 aligncenter\"><img decoding=\"async\" class=\"grey-border\" src=\"https:\/\/www.maxqda.com\/wp\/wp-content\/uploads\/sites\/2\/WordExplorerExampleCrazy.jpg\" alt=\"Screenshot des Wort Explorers mit h\u00e4ufiger Nutzung des Begriffs 'crazy' in Dokumenten und Codes\" \/><\/div>\r\n<p>Selbst ohne die Transkripte zu lesen, springen die Muster ins Auge. Der Begriff &#8222;crazy&#8220; tauchte 47-mal in 8 der 13 Interviews auf. Schon das allein erm\u00f6glichte es mir, emotional aufgeladene Stellen schnell zu identifizieren. Aber mehr noch: Es half mir, bessere Fragen zu stellen. Warum kam der Begriff in manchen Interviews h\u00e4ufiger vor als in anderen? Lag es am Fehlen des Begriffs in den restlichen Interviews oder am Fehlen des dahinterliegenden Gef\u00fchls?<\/p>\r\n<p>Das brachte mich dazu, nach synonymen Ausdr\u00fccken zu suchen, die ich zuvor \u00fcbersehen hatte \u2013 Formulierungen wie &#8222;das ist irre,&#8220; &#8222;man will schreien&#8220; oder auch sarkastische Nebenbemerkungen. Ich begann, affektive Vokabeln gezielter zu erfassen und konnte endlich pr\u00fcfen, ob Themen wie Ungl\u00e4ubigkeit oder Absurdit\u00e4t blo\u00dfe Ausnahmen oder Teil eines umfassenderen affektiven Musters waren.<\/p>\r\n<h3>Vom Chaos zu den Kategorien<\/h3>\r\n<p>Als ich die Arbeit geschrieben habe,\u00a0 hatte MAXQDA noch keine erweiterte Suche nach Synonymen (heute \u00fcbrigens schon, siehe hier), also habe ich meine eigene entwickelt. Ich habe Listen erstellt: Ausdr\u00fccke der Emp\u00f6rung, S\u00e4tze, die Unglauben zeigen, sarkastische Einzeiler. Und dann habe ich sie durch den Wort Explorer laufen lassen.<\/p>\r\n<p>Je weiter ich kam, desto klarer wurde mir, dass sich \u00e4hnliche emotionale Ausdr\u00fccke gruppierten. Sie tauchten in Interviews auf, die ich ganz anders codiert hatte. Das war kein Rauschen, sondern ein Signal.<\/p>\r\n<p>Was ich fand, best\u00e4tigte nicht nur meine Vermutung. Es gab meiner These R\u00fcckhalt, wenn auch nicht auf Anhieb. Es war ein langsamer, iterativer Prozess, bei dem ich verschiedene W\u00f6rter und Ausdr\u00fccke eingab, ihren Kontext \u00fcberpr\u00fcfte und nach und nach Muster erkannte.<\/p>\r\n<p>Die Teilnehmenden haben nicht einfach nur Dampf abgelassen. Einige haben ihre eigene geistige Gesundheit in Frage gestellt. Andere haben die Sprache der Absurdit\u00e4t, die sie beobachtet und erlebt haben, auf \u00fcberraschend bewusste Weise verwendet und sie umgedreht, um die Inkoh\u00e4renz der Systeme hervorzuheben, die sie einzuschr\u00e4nken versuchen.<\/p>\r\n<p>Diese Erkenntnis l\u00f6ste einen weiteren Analysezyklus aus, in dem sich In-vivo-Codes wie \u201edas ist verr\u00fcckt\u201c zu konzeptionellen Kategorien wie \u201ediskursive Absurdit\u00e4t\u201c und \u201esubversive Absurdit\u00e4t\u201c entwickelten.<\/p>\r\n<p>Das Tolle am Wort Explorer ist, dass man, sobald man auf die Anzahl der Treffer f\u00fcr einen Suchbegriff klickt, eine interaktive Liste von Segmenten erh\u00e4lt. Man kann sie schnell im Ergebnisfenster \u00fcberpr\u00fcfen oder auf einen Eintrag klicken, um direkt zum Kontext im Dokument zu springen, was entscheidend ist, wenn man herausfinden will, ob ein Wort in \u00e4hnlicher Weise verwendet wird.<\/p>\r\n<p>Die meisten der emotional aufgeladenen Beispiele, mit denen ich gearbeitet habe, kann ich aus Gr\u00fcnden der Vertraulichkeit und politischen Sensibilit\u00e4t hier nicht teilen.<\/p>\r\n<p>Um diesen Prozess zu veranschaulichen, habe ich jedoch ein neutraleres Beispiel beigef\u00fcgt, das ich ohne Bedenken ver\u00f6ffentlichen kann.<\/p>\r\n<p>Der Begriff \u201einsane\u201c (verr\u00fcckt) war Teil meiner Synonymliste f\u00fcr Ausdr\u00fccke der Ungl\u00e4ubigkeit. Lesende werden feststellen, dass ich einen der Treffer mit einem Stopp-Symbol markiert habe, da diese Erw\u00e4hnung in einer nachfolgenden kl\u00e4renden Frage enthalten war und nicht von dem Teilnehmer stammt. Durch diese Markierung kann ich ihn bei der automatischen Codierung aller Suchtreffer ausschlie\u00dfen.<\/p>\r\n<div class=\"large-12 aligncenter\"><img decoding=\"async\" class=\"grey-border\" src=\"https:\/\/www.maxqda.com\/wp\/wp-content\/uploads\/sites\/2\/WordExplorerResultsInsane.jpg\" alt=\"Screenshot des Wort Explorers, der zeigt, wie oft das Wort \u201einsane\u201c in den Interviews auftaucht.\" \/><\/div>\r\n<p>Um diesen Prozess zu veranschaulichen, habe ich jedoch ein neutraleres Beispiel beigef\u00fcgt, das ich ohne Bedenken ver\u00f6ffentlichen kann.<\/p>\r\n<p>Der Begriff \u201einsane\u201c (verr\u00fcckt) war Teil meiner Synonymliste f\u00fcr Ausdr\u00fccke der Ungl\u00e4ubigkeit. Lesende werden feststellen, dass ich einen der Treffer mit einem Stopp-Symbol markiert habe, da diese Erw\u00e4hnung in einer nachfolgenden kl\u00e4renden Frage enthalten war und nicht von dem Teilnehmer stammt. Durch diese Markierung kann ich ihn bei der automatischen Codierung aller Suchtreffer ausschlie\u00dfen.<\/p>\r\n<h3>Was sich ge\u00e4ndert hat: Von Fragmenten zum Fokus<\/h3>\r\n<p>Hier ist, was sich in meinem Prozess ge\u00e4ndert hat und warum Wort Explorer am Ende mehr als nur eine coole Funktion geworden ist.<\/p>\r\n<ul>\r\n\t<li><strong>Versteckte Muster, gemeinsame Untert\u00f6ne<\/strong> <br \/>\r\nWort Explorer hat mir geholfen zu erkennen, dass das, was wie zuf\u00e4llige Ausdr\u00fccke aussah, alles andere als zuf\u00e4llig war. Zuerst dachte ich, es handele sich um einmalige emotionale Ausbr\u00fcche. Aber je mehr ich suchte, desto mehr sah ich, dass sie sich in jedem Interview wiederholten. Das waren keine isolierten Gef\u00fchle, sondern gemeinsame emotionale Str\u00f6mungen. Das hat meine Herangehensweise an die Daten ver\u00e4ndert. Es ging nicht mehr nur darum, Themen zu identifizieren, sondern emotionale Logiken nachzuvollziehen. Ungl\u00e4ubigkeit, Ironie und Entfremdung waren ein Mittel der politischen Erfahrung. Und die Teilnehmer? Die hatten die Analyse bereits gemacht. Ich habe endlich richtig zugeh\u00f6rt.<\/li>\r\n\t<li><strong>Absurdit\u00e4t als Anker<\/strong> <br \/>\r\nEin emotionales Thema tauchte immer wieder auf: Absurdit\u00e4t. Nicht immer direkt benannt, aber immer da, in Sarkasmus, in Nebenbemerkungen, in den Momenten, in denen die Leute \u00fcber die Inkoh\u00e4renz des Ganzen lachten. Mit dem Wort Explorer konnte ich diesen subtilen Faden verfolgen, und das hat alles ver\u00e4ndert. Absurdit\u00e4t war nicht nur eine Stimmung, sondern eine strukturelle Reaktion auf Widerspr\u00fcche, Unterdr\u00fcckung und politische Manipulation. Sie wurde zum Kernkonzept, das alles andere zusammenhielt. Pl\u00f6tzlich hatte meine These eine Erz\u00e4hlung.<\/li>\r\n\t<li><strong>Widerspruch als Klarheit<\/strong> <br \/>\r\nDieses Tool gab Dingen Gestalt, die ich noch nicht klar gesehen hatte. Ich hatte Themen wie Unterdr\u00fcckung, Identit\u00e4tskontrolle und Legitimit\u00e4t kodiert. Sie waren alle da. Aber Wort Explorer beleuchtete den affektiven Faden, der in meiner urspr\u00fcnglichen Kategorisierung nicht offensichtlich war: Absurdit\u00e4t. Das waren nicht nur parallele Themen, die im Chaos schwebten \u2013 sie waren durch eine gemeinsame affektive Logik verbunden. Absurdit\u00e4t war kein Umweg von den Daten, sondern der Klebstoff, der die Widerspr\u00fcche sinnvoll machte. Sie gab den Ergebnissen narrative Koh\u00e4renz statt nur analytischer Fragmentierung.<\/li>\r\n\t<li><strong>Von allem zu dem, was z\u00e4hlt<\/strong> Einer der schwierigsten Aspekte qualitativer Arbeit ist das Bauchgef\u00fchl, dass alles wichtig ist. Wie k\u00f6nnte ich aus ethischen Gr\u00fcnden irgendetwas \u00fcberspringen? Ich hatte Hunderte von Seiten mit Transkripten und das tiefe Bed\u00fcrfnis, jeden Satz zu w\u00fcrdigen. Aber Wort Explorer machte es einfacher, einen Schritt zur\u00fcckzutreten. Es zeigte mir, was am h\u00e4ufigsten vorkam, was die gr\u00f6\u00dfte emotionale Wirkung hatte und was in verschiedenen Kontexten immer wieder auftauchte. Es gab mir die Erlaubnis, mich zu fokussieren. Und dieser Wechsel vom Codieren aller Daten zum Verfolgen von Mustern war es schlie\u00dflich, der das Schreiben m\u00f6glich machte.<\/li>\r\n<\/ul>\r\n<h2>Schlussgedanken: Klarheit im Chaos<\/h2>\r\n<p>R\u00fcckblickend hat mich der MAXQDA Wort Explorer nicht nur bei der Analyse meiner Daten unterst\u00fctzt, sondern mir auch dabei geholfen, diese zu \u00fcberstehen. Es hat mich aus dem endlosen Scrollen durch Codes herausgeholt und an einen Ort gebracht, an dem ich endlich die Form meiner Ergebnisse erkennen konnte. Es hat mir Halt gegeben in einem Projekt, das sich oft wie emotionaler Treibsand anf\u00fchlte.<\/p>\r\n<p>F\u00fcr alle, die sich durch schwierige, emotional chaotische Recherchen k\u00e4mpfen: Untersch\u00e4tzt nicht, was ein gut eingesetztes Tool leisten kann.<\/p>\r\n<p>Der Wort Explorer hat die Daten nicht vereinfacht und die emotionale Belastung nicht verringert, aber er hat mir eine M\u00f6glichkeit gegeben, mit beidem umzugehen. Und in einem Projekt wie meinem hat das den entscheidenden Unterschied gemacht.<\/p>\r\n<p>Wer also vor einer Wand aus chaotischen Transkripten sitzt und auf ein Signal inmitten des L\u00e4rms hofft, sollte einfach mal irgendetwas in den Wort Explorer eingeben. Auch wenn da m\u00f6glicherweise nicht sofort Antworten zu finden sind, vielleicht findet sich ein Weg hinein.<\/p>\r\n<p>&nbsp;<\/p>\r\n<h2>\u00dcber den Autoren<\/h2>\r\n<div class=\"row\">\r\n<div class=\"large-3 alignleft\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.maxqda.com\/wp\/wp-content\/uploads\/sites\/2\/Xan-scaled.jpg\" \/><\/div>\r\n<div class=\"large-8 alignright\">\r\n<p>Xan (er\/ihm) hat gerade seinen Master in Soziologie gemacht. Jetzt arbeitet er bei VERBI Software, wo er AI-Prototypen testet, \u00fcber MAXQDA schreibt und ab und zu Erinnerungen an seine Abschlussarbeit \u00fcbersteht, indem er sie in Blogbeitr\u00e4ge verwandelt.<\/p>\r\n<\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Xans Forschungsreise mit dem MAXQDA Wort Explorer Seien wir mal ehrlich: Qualitative Forschung kann ganz sch\u00f6n brutal sein. Ich habe gerade letzten Monat meine Masterarbeit abgegeben, und ganz ehrlich? Ich hab mich immer noch nicht ganz von dieser intensiven T\u00e4tigkeit erholt. Da hilft es, sich auf die positiven Erfahrungen zu besinnen. Eine davon war die [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":126861,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[28],"tags":[],"class_list":["post-129608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-favorite-features"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Favorite Features: Wort-Explorer | MAXQDA<\/title>\n<meta name=\"description\" content=\"Erfahren Sie alles \u00fcber den MAXQDA Wort-Explorer. Ein Tool, mit dem Sie in Ihrem MAXQDA-Projekt nach W\u00f6rtern oder Phrasen suchen k\u00f6nnen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Favorite Features: Wort-Explorer\" \/>\n<meta property=\"og:description\" content=\"Xans Forschungsreise mit dem MAXQDA Wort Explorer Seien wir mal ehrlich: Qualitative Forschung kann ganz sch\u00f6n brutal sein. Ich habe gerade letzten Monat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer\" \/>\n<meta property=\"og:site_name\" content=\"MAXQDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MAXQDA\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-26T09:17:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-28T10:55:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/blogbeitrag-Stern.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"wpchristin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@VerbiSoftware\" \/>\n<meta name=\"twitter:site\" content=\"@VerbiSoftware\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"wpchristin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer\"},\"author\":{\"name\":\"wpchristin\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#\\\/schema\\\/person\\\/00700cd54ca021a927e79c19e23784a6\"},\"headline\":\"Favorite Features: Wort-Explorer\",\"datePublished\":\"2025-05-26T09:17:40+00:00\",\"dateModified\":\"2025-05-28T10:55:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer\"},\"wordCount\":2265,\"publisher\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/blogbeitrag-Stern.png\",\"articleSection\":[\"Favorite Features\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer\",\"name\":\"Favorite Features: Wort-Explorer | MAXQDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/blogbeitrag-Stern.png\",\"datePublished\":\"2025-05-26T09:17:40+00:00\",\"dateModified\":\"2025-05-28T10:55:25+00:00\",\"description\":\"Erfahren Sie alles \u00fcber den MAXQDA Wort-Explorer. Ein Tool, mit dem Sie in Ihrem MAXQDA-Projekt nach W\u00f6rtern oder Phrasen suchen k\u00f6nnen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer#primaryimage\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/blogbeitrag-Stern.png\",\"contentUrl\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/blogbeitrag-Stern.png\",\"width\":400,\"height\":400,\"caption\":\"Favorite MAXQDA Features\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/blogpost\\\/favorite-features-wort-explorer#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Favorite Features: Wort-Explorer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/\",\"name\":\"MAXQDA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#organization\",\"name\":\"MAXQDA\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo.png\",\"width\":\"1000\",\"height\":\"200\",\"caption\":\"MAXQDA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MAXQDA\\\/\",\"https:\\\/\\\/x.com\\\/VerbiSoftware\",\"https:\\\/\\\/www.instagram.com\\\/maxqda\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/MAXQDA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#\\\/schema\\\/person\\\/00700cd54ca021a927e79c19e23784a6\",\"name\":\"wpchristin\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Favorite Features: Wort-Explorer | MAXQDA","description":"Erfahren Sie alles \u00fcber den MAXQDA Wort-Explorer. Ein Tool, mit dem Sie in Ihrem MAXQDA-Projekt nach W\u00f6rtern oder Phrasen suchen k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer","og_locale":"de_DE","og_type":"article","og_title":"Favorite Features: Wort-Explorer","og_description":"Xans Forschungsreise mit dem MAXQDA Wort Explorer Seien wir mal ehrlich: Qualitative Forschung kann ganz sch\u00f6n brutal sein. Ich habe gerade letzten Monat","og_url":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer","og_site_name":"MAXQDA","article_publisher":"https:\/\/www.facebook.com\/MAXQDA\/","article_published_time":"2025-05-26T09:17:40+00:00","article_modified_time":"2025-05-28T10:55:25+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/blogbeitrag-Stern.png","type":"image\/png"}],"author":"wpchristin","twitter_card":"summary_large_image","twitter_creator":"@VerbiSoftware","twitter_site":"@VerbiSoftware","twitter_misc":{"Verfasst von":"wpchristin","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer#article","isPartOf":{"@id":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer"},"author":{"name":"wpchristin","@id":"https:\/\/www.maxqda.com\/de\/#\/schema\/person\/00700cd54ca021a927e79c19e23784a6"},"headline":"Favorite Features: Wort-Explorer","datePublished":"2025-05-26T09:17:40+00:00","dateModified":"2025-05-28T10:55:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer"},"wordCount":2265,"publisher":{"@id":"https:\/\/www.maxqda.com\/de\/#organization"},"image":{"@id":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer#primaryimage"},"thumbnailUrl":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/blogbeitrag-Stern.png","articleSection":["Favorite Features"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer","url":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer","name":"Favorite Features: Wort-Explorer | MAXQDA","isPartOf":{"@id":"https:\/\/www.maxqda.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer#primaryimage"},"image":{"@id":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer#primaryimage"},"thumbnailUrl":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/blogbeitrag-Stern.png","datePublished":"2025-05-26T09:17:40+00:00","dateModified":"2025-05-28T10:55:25+00:00","description":"Erfahren Sie alles \u00fcber den MAXQDA Wort-Explorer. Ein Tool, mit dem Sie in Ihrem MAXQDA-Projekt nach W\u00f6rtern oder Phrasen suchen k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer#primaryimage","url":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/blogbeitrag-Stern.png","contentUrl":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/blogbeitrag-Stern.png","width":400,"height":400,"caption":"Favorite MAXQDA Features"},{"@type":"BreadcrumbList","@id":"https:\/\/www.maxqda.com\/de\/blogpost\/favorite-features-wort-explorer#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.maxqda.com\/de\/"},{"@type":"ListItem","position":2,"name":"Favorite Features: Wort-Explorer"}]},{"@type":"WebSite","@id":"https:\/\/www.maxqda.com\/de\/#website","url":"https:\/\/www.maxqda.com\/de\/","name":"MAXQDA","description":"","publisher":{"@id":"https:\/\/www.maxqda.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maxqda.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.maxqda.com\/de\/#organization","name":"MAXQDA","url":"https:\/\/www.maxqda.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.maxqda.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo.png","contentUrl":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo.png","width":"1000","height":"200","caption":"MAXQDA"},"image":{"@id":"https:\/\/www.maxqda.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MAXQDA\/","https:\/\/x.com\/VerbiSoftware","https:\/\/www.instagram.com\/maxqda\/","https:\/\/www.youtube.com\/user\/MAXQDA"]},{"@type":"Person","@id":"https:\/\/www.maxqda.com\/de\/#\/schema\/person\/00700cd54ca021a927e79c19e23784a6","name":"wpchristin"}]}},"_links":{"self":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/posts\/129608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/comments?post=129608"}],"version-history":[{"count":0,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/posts\/129608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/media\/126861"}],"wp:attachment":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/media?parent=129608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/categories?post=129608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/tags?post=129608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}