{"id":124671,"date":"2024-05-07T11:47:31","date_gmt":"2024-05-07T10:47:31","guid":{"rendered":"https:\/\/www.maxqda.com\/de\/?page_id=124671"},"modified":"2026-02-23T16:50:42","modified_gmt":"2026-02-23T15:50:42","slug":"drittdienstleister","status":"publish","type":"page","link":"https:\/\/www.maxqda.com\/de\/drittdienstleister","title":{"rendered":"Drittdienstleister und Unterauftragsverarbeiter"},"content":{"rendered":"<h1>Drittdienstleister und Unterauftragsverarbeiter<\/h1>\r\n\r\n<p>F\u00fcr unsere Cloud-basierten und KI-gest\u00fctzten Funktionen arbeiten wir mit sorgf\u00e4ltig ausgew\u00e4hlten Drittanbietern zusammen. Diese Dienstleister erhalten nur die Daten, die f\u00fcr die Erf\u00fcllung der gew\u00fcnschten Aufgabe notwendig sind. Mit allen eingesetzten Dienstleistern wurden die erforderlichen vertraglichen Vereinbarungen geschlossen, insbesondere Auftragsverarbeitungsvertr\u00e4ge gem\u00e4\u00df Art. 28 DSGVO.<\/p> <p>Sofern eine Verarbeitung personenbezogener Daten in einem Drittland erfolgt, stellen wir sicher, dass hierf\u00fcr geeignete Garantien bestehen, etwa durch einen Angemessenheitsbeschluss der Europ\u00e4ischen Kommission oder den Abschluss von Standardvertragsklauseln (SCC).<\/p>\r\n<p>Nachstehend finden Sie weitere Details zu unseren Drittanbietern, aufgelistet nach Add-On-Funktion und\/oder Anwendung.<\/p>\r\n\r\n\r\n<h3>AI Assist<\/h3>\r\n<div class=\"landing-page-mx2022-row\">\r\n    <div class=\"large-12 small-12 columns\" style=\"margin-bottom:45px;\">\r\n        <ul class=\"accordion\" data-accordion=\"\" id=\"aiassist\">\r\n            <!--\r\n\t\t\t<li class=\"accordion-navigation\"> <a href=\"#panel-a\">OpenAI, LLC<\/a>\r\n                <div id=\"panel-a\" class=\"content\">\r\n                    <p><strong>Dienstleister:<\/strong> OpenAI, LLC<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 3180 18th St., San Francisco, CA 94110, USA<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> USA<\/p>\r\n                    <p><strong>Datenschutzrechtlichen Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> SCC<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Erstellung von Zusammenfassungen, Erl\u00e4uterung von Begriffen, Chat mit Daten, Code-Vorschl\u00e4ge.<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> Erzeugen einer Antwort mit einem Large Language Modell<\/p>\r\n\t\t\t\t\t<p><strong>Dauer der Verarbeitung:<\/strong> Die vom Kunden bereitgestellten Daten werden bei Wegfall der Erforderlichkeit der Verarbeitung umgehend, sp\u00e4testens jedoch nach 30 Tagen, gel\u00f6scht.<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong> <a href=\"https:\/\/trust.openai.com\/\">https:\/\/trust.openai.com\/<\/a><\/p>\r\n\t\t\t\t\t<p><strong>Nutzungsbedingungen:<\/strong> <a href=\"https:\/\/openai.com\/policies\/usage-policies\">https:\/\/openai.com\/policies\/usage-policies<\/a>; <a href=\"https:\/\/openai.com\/policies\/sharing-publication-policy\">https:\/\/openai.com\/policies\/sharing-publication-policy<\/a><\/p>\r\n\t\t\t\t\t<p><strong>Anmerkungen:<\/strong> OpenAI nutzt Ihre Daten nicht zu Trainingszwecken der eingesetzten k\u00fcnstlichen Intelligenz.<\/p>\r\n                <\/div>\r\n            <\/li>\r\n\t\t\t\r\n\t\t\t-->\r\n            <li class=\"accordion-navigation\"> <a href=\"#panel-b\">Amazon Web Services EMEA SARL (AWS)<\/a>\r\n                <div id=\"panel-b\" class=\"content\">\r\n                    <p><strong>Dienstleister:<\/strong> Amazon Web Services EMEA SARL (AWS)<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 38 Avenue John F. Kennedy, L-1855, Luxemburg.<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> Deutschland, Frankreich<\/p>\r\n                    <p><strong>Datenschutzrechtlichen Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> Nicht erforderlich<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Bedrock: Erstellung von Zusammenfassungen, Erl\u00e4uterung von Begriffen, Chat mit Daten, Code-Vorschl\u00e4ge.<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> Erzeugen einer Antwort mit einem Large Language Modell<\/p>\r\n\t\t\t\t\t<p><strong>Dauer der Verarbeitung:<\/strong> Die vom Kunden bereitgestellten Daten werden bei Wegfall der Erforderlichkeit der Verarbeitung umgehend gel\u00f6scht.<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong> <a href=\"https:\/\/aws.amazon.com\/de\/security\">https:\/\/aws.amazon.com\/de\/security<\/a><\/p>\r\n\t\t\t\t\t<p><strong>Nutzungsbedingungen:<\/strong> <a href=\"https:\/\/aws.amazon.com\/service-terms\">https:\/\/aws.amazon.com\/service-terms<\/a> (insbesondere Ziffer 50 AWS Machine Learning and Artificial Intelligence Services) <\/p>\r\n\t\t\t\t\t<p><strong>Anmerkungen:<\/strong> AWS nutzt Ihre Daten nicht zu Trainingszwecken der eingesetzten k\u00fcnstlichen Intelligenz.<\/p>\r\n                <\/div>\r\n            <\/li>\r\n\t\t\t <li class=\"accordion-navigation\"> <a href=\"#panel-c\">Amazon Web Services EMEA SARL (AWS) &#8211; Infrastruktur<\/a>\r\n                <div id=\"panel-c\" class=\"content\">\r\n                    <p><strong>Dienstleister:<\/strong> Amazon Web Services EMEA SARL (AWS)<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 38 Avenue John F. Kennedy, L-1855, Luxemburg.<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> Deutschland<\/p>\r\n                    <p><strong>Datenschutzrechtliche Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> Nicht erforderlich<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Hosting der Infrastruktur<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> Speicherung der erforderlichen Daten zur Bereitstellung des Dienstes<\/p>\r\n\t\t\t\t\t<p><strong>Dauer der Verarbeitung:<\/strong> Die vom Kunden bereitgestellten Daten werden bei Wegfall der Erforderlichkeit der Verarbeitung umgehend gel\u00f6scht.<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong> <a href=\"https:\/\/aws.amazon.com\/de\/security\">https:\/\/aws.amazon.com\/de\/security<\/a><\/p>\r\n\t\t\t\t\t<p><strong>Nutzungsbedingungen:<\/strong> <a href=\"https:\/\/aws.amazon.com\/service-terms\">https:\/\/aws.amazon.com\/service-terms<\/a> <\/p>\r\n                <\/div>\r\n            <\/li>\r\n\t  <li class=\"accordion-navigation\"> <a href=\"#panel-d\">Google Cloud EMEA Limited<\/a>\r\n                <div id=\"panel-d\" class=\"content\">\r\n                    <p><strong>Dienstleister:<\/strong> Google Cloud EMEA Limited<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 70 Sir John Rogerson\u2019s Quay, Dublin 2, Ireland.<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> Germany, Netherlands, France, Belgium, Spain, Italy, Poland, Finland<\/p>\r\n                    <p><strong>Datenschutzrechtliche Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> Not Required<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Vertex AI: summarizing, term explanation, data chat, code suggestions.<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> Generating a response with a large language model<\/p>\r\n                    <p><strong>Dauer der Verarbeitung:<\/strong> Customer-provided data will be deleted promptly once processing is no longer required.<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong>  <a href=\"https:\/\/cloud.google.com\/docs\/security?hl=de\"> https:\/\/cloud.google.com\/docs\/security?hl=de<\/a><\/p> \r\n                    <p><strong>Nutzungsbedingungen:<\/strong> <a href=\"https:\/\/cloud.google.com\/terms\"> https:\/\/cloud.google.com\/terms<\/a><\/p>\r\n                    <p><strong>Anmerkungen:<\/strong> Google does not use your data for training its AI. See <a href=\"https:\/\/cloud.google.com\/vertex-ai\/generative-ai\/docs\/data-governance\">https:\/\/cloud.google.com\/vertex-ai\/generative-ai\/docs\/data-governance<\/a> for details on how Google processes and governs customer data.<\/p>\r\n\r\n\r\n                <\/div>\r\n            <\/li>\r\n\t\t\t\r\n\t\t\t<!--li class=\"accordion-navigation\"> <a href=\"#panel-j\">RunPod Inc.<\/a>\r\n                <div id=\"panel-j\" class=\"content\">\r\n                    <p><strong>Dienstleister:<\/strong> RunPod Inc.<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 1181 Nixon Dr. #1158, Moorestown, NJ 08057, United States<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> Rum\u00e4nien<\/p>\r\n                    <p><strong>Datenschutzrechtliche Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> Nicht erforderlich<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Konvertierung von PDF-Dateien<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> Extrahieren von Text aus PDF-Dokumenten mit k\u00fcnstlicher Intelligenz<\/p>\r\n                    <p><strong>Dauer der Verarbeitung:<\/strong> Die vom Kunden bereitgestellten Daten werden bei Wegfall der Erforderlichkeit der Verarbeitung umgehend gel\u00f6scht.<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong>  <a href=\"https:\/\/www.runpod.io\/compliance\">runpod.io\/compliance<\/a><\/p> \r\n                    <p><strong>Nutzungsbedingungen:<\/strong> <a href=\"https:\/\/www.runpod.io\/legal\/terms-of-service\">runpod.io\/legal\/terms-of-service <\/a><\/p>\r\n                <\/div>\r\n            <\/li-->\r\n\t\t\t\r\n\t\t\t<\/ul>\r\n\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n<h3>MAXQDA Tailwind<\/h3>\r\n<div class=\"landing-page-mx2022-row\">\r\n    <div class=\"large-12 small-12 columns\" style=\"margin-bottom:45px; border:none;\">\r\n        <ul class=\"accordion\" data-accordion=\"\" id=\"teamcloud\">\r\n            <li class=\"accordion-navigation\"> <a href=\"#panel-e\">Google Cloud EMEA Limited<\/a>\r\n                <div id=\"panel-e\" class=\"content\">\r\n                    <p><strong>Dienstleister:<\/strong> Google Cloud EMEA Limited<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 70 Sir John Rogerson\u2019s Quay, Dublin 2, Ireland.<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> Germany, Netherlands, France, Belgium, Spain, Italy, Poland, Finland<\/p>\r\n                    <p><strong>Datenschutzrechtliche Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> Not Required<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Vertex AI: summarization, theme identification, data-based chat interactions, report generation<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> Generating a response with a large language model<\/p>\r\n                    <p><strong>Dauer der Verarbeitung:<\/strong> Customer-provided data will be deleted promptly once processing is no longer required.<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong>  <a href=\"https:\/\/cloud.google.com\/docs\/security?hl=de\"> https:\/\/cloud.google.com\/docs\/security?hl=de<\/a><\/p> \r\n                    <p><strong>Nutzungsbedingungen:<\/strong> <a href=\"https:\/\/cloud.google.com\/terms\"> https:\/\/cloud.google.com\/terms<\/a><\/p>\r\n                    <p><strong>Anmerkungen:<\/strong> Google does not use your data for training its AI. See <a href=\"https:\/\/cloud.google.com\/vertex-ai\/generative-ai\/docs\/data-governance\">https:\/\/cloud.google.com\/vertex-ai\/generative-ai\/docs\/data-governance<\/a> for details on how Google processes and governs customer data.<\/p>\r\n\r\n\r\n                <\/div>\r\n            <\/li>\r\n\t\t\t<li class=\"accordion-navigation\"> <a href=\"#panel-f\">Amazon Web Services EMEA SARL (AWS) &#8211; Infrastructure<\/a>\r\n                <div id=\"panel-f\" class=\"content\">\r\n                   <p><strong>Dienstleister:<\/strong> Amazon Web Services EMEA SARL (AWS)<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 38 Avenue John F. Kennedy, L-1855, Luxemburg.<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> Deutschland<\/p>\r\n                    <p><strong>Datenschutzrechtliche Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> Nicht erforderlich<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Hosting der Infrastruktur<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> Speicherung der erforderlichen Daten zur Bereitstellung des Dienstes<\/p>\r\n\t\t\t\t\t<p><strong>Dauer der Verarbeitung:<\/strong> Die vom Kunden bereitgestellten Daten werden bei Wegfall der Erforderlichkeit der Verarbeitung umgehend gel\u00f6scht.<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong> <a href=\"https:\/\/aws.amazon.com\/de\/security\">https:\/\/aws.amazon.com\/de\/security<\/a><\/p>\r\n\t\t\t\t\t<p><strong>Nutzungsbedingungen:<\/strong> <a href=\"https:\/\/aws.amazon.com\/service-terms\">https:\/\/aws.amazon.com\/service-terms<\/a> <\/p>\r\n                <\/div>\r\n            <\/li>\r\n\t\t\t<li class=\"accordion-navigation\"> <a href=\"#panel-k\">RunPod Inc.<\/a>\r\n                <div id=\"panel-k\" class=\"content\">\r\n                    <p><strong>Dienstleister:<\/strong> RunPod Inc.<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 1181 Nixon Dr. #1158, Moorestown, NJ 08057, United States<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> Rum\u00e4nien<\/p>\r\n                    <p><strong>Datenschutzrechtliche Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> Nicht erforderlich<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Konvertierung von PDF-Dateien<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> Extrahieren von Text aus PDF-Dokumenten mit k\u00fcnstlicher Intelligenz<\/p>\r\n                    <p><strong>Dauer der Verarbeitung:<\/strong> Die vom Kunden bereitgestellten Daten werden bei Wegfall der Erforderlichkeit der Verarbeitung umgehend gel\u00f6scht.<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong>  <a href=\"https:\/\/www.runpod.io\/compliance\">runpod.io\/compliance<\/a><\/p> \r\n                    <p><strong>Nutzungsbedingungen:<\/strong> <a href=\"https:\/\/www.runpod.io\/legal\/terms-of-service\">runpod.io\/legal\/terms-of-service <\/a><\/p>\r\n                <\/div>\r\n            <\/li>\r\n\t\t\t\r\n        <\/ul>\r\n    <\/div>\r\n<\/div>\r\n\r\n\r\n<h3>MAXQDA TeamCloud<\/h3>\r\n<div class=\"landing-page-mx2022-row\">\r\n    <div class=\"large-12 small-12 columns\" style=\"margin-bottom:45px;\">\r\n        <ul class=\"accordion\" data-accordion=\"\">\r\n                   \r\n\t\t\t <li class=\"accordion-navigation\"> <a href=\"#panel-g\">Amazon Web Services EMEA SARL (AWS) &#8211; Infrastruktur<\/a>\r\n                <div id=\"panel-g\" class=\"content\">\r\n                    <p><strong>Dienstleister:<\/strong> Amazon Web Services EMEA SARL (AWS)<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 38 Avenue John F. Kennedy, L-1855, Luxemburg.<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> Deutschland<\/p>\r\n                    <p><strong>Datenschutzrechtlichen Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> Nicht erforderlich<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Hosting der Infrastruktur<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> Speicherung der erforderlichen Daten zur Bereitstellung des Dienstes<\/p>\r\n\t\t\t\t\t<p><strong>Dauer der Verarbeitung:<\/strong> Die Dauer der Vereinbarung richtet sich nach der Dauer des TeamCloud-Abonnements des Kunden. Drei Monate nach Vertragsende werden die Projektdaten des Kunden aus der TeamCloud gel\u00f6scht.<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong> <a href=\"https:\/\/aws.amazon.com\/de\/security\">https:\/\/aws.amazon.com\/de\/security<\/a><\/p>\r\n\t\t\t\t\t<p><strong>Nutzungsbedingungen:<\/strong> <a href=\"https:\/\/aws.amazon.com\/service-terms\">https:\/\/aws.amazon.com\/service-terms<\/a> <\/p>\r\n                <\/div>\r\n            <\/li>\r\n\t\t\t\r\n\t\t\t<\/ul>\r\n\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n            \r\n\r\n<h3>MAXQDA Transcription<\/h3>\r\n<div class=\"landing-page-mx2022-row\">\r\n    <div class=\"large-12 small-12 columns\" style=\"margin-bottom:45px;\">\r\n        <ul class=\"accordion\" data-accordion=\"\">\r\n           \r\n            \r\n\t\t\t <li class=\"accordion-navigation\"> <a href=\"#panel-h\">Amazon Web Services EMEA SARL (AWS) &#8211; Infrastruktur<\/a>\r\n                <div id=\"panel-h\" class=\"content\">\r\n                    <p><strong>Dienstleister:<\/strong> Amazon Web Services EMEA SARL (AWS)<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 38 Avenue John F. Kennedy, L-1855, Luxemburg.<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> Deutschland<\/p>\r\n                    <p><strong>Datenschutzrechtlichen Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> Nicht erforderlich<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Hosting der Infrastruktur<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> Speicherung der erforderlichen Daten zur Bereitstellung des Dienstes<\/p>\r\n\t\t\t\t\t<p><strong>Dauer der Verarbeitung:<\/strong> Die vom Kunden bereitgestellten Daten werden bei Wegfall der Erforderlichkeit der Verarbeitung umgehend gel\u00f6scht. F\u00fcr die hochgeladene Mediendatei erfolgt die L\u00f6schung 7 Tage nach Upload. Das erstellte Transkript l\u00f6schen wir 7 Tage nach Download durch den Kunden, wenn dieser nicht vorher die L\u00f6schung veranlasst.<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong> <a href=\"https:\/\/aws.amazon.com\/de\/security\">https:\/\/aws.amazon.com\/de\/security<\/a><\/p>\r\n\t\t\t\t\t<p><strong>Nutzungsbedingungen:<\/strong> <a href=\"https:\/\/aws.amazon.com\/service-terms\">https:\/\/aws.amazon.com\/service-terms<\/a> <\/p>\r\n                <\/div>\r\n            <\/li>\r\n\t\t\t <li class=\"accordion-navigation\"> <a href=\"#panel-i\">Cantab Research Limited (trading as &#8222;Speechmatics&#8220;)<\/a>\r\n                <div id=\"panel-i\" class=\"content\">\r\n                    <p><strong>Dienstleister:<\/strong> Cantab Research Limited<\/p>\r\n                    <p><strong>Anschrift:<\/strong> 296 Cambridge Science Park, Milton Road, Cambridge, CB4 0WD, United Kingdom<\/p>\r\n                    <p><strong>Ort der Verarbeitung personenbezogener Daten:<\/strong> Niederlande<\/p>\r\n                    <p><strong>Datenschutzrechtlichen Garantien bei Verarbeitung au\u00dferhalb des EWR:<\/strong> Nicht erforderlich<\/p>\r\n                    <p><strong>Gegenstand der Verarbeitung:<\/strong> Transkription<\/p>\r\n\t\t\t\t\t<p><strong>Dauer der Verarbeitung:<\/strong> Die vom Kunden bereitgestellten Daten werden bei Wegfall der Erforderlichkeit der Verarbeitung umgehend gel\u00f6scht.<\/p>\r\n                    <p><strong>Art der Verarbeitung:<\/strong> \u00dcbersetzung einer Mediendatei in Text mittels K\u00fcnstlicher Intelligenz<\/p>\r\n\t\t\t\t\t<p><strong>Ma\u00dfnahmen zur Datensicherheit:<\/strong> <a href=\"https:\/\/www.speechmatics.com\/security\">https:\/\/www.speechmatics.com\/security<\/a><\/p>\r\n\t\t\t\t\t<p><strong>Nutzungsbedingungen:<\/strong>  <a href=\"https:\/\/www.speechmatics.com\/legal\/terms-of-service\">https:\/\/www.speechmatics.com\/legal\/terms-of-service<\/a><\/p>\r\n                <\/div>\r\n            <\/li>\r\n\t\t\t<\/ul>\r\n\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n            ","protected":false},"excerpt":{"rendered":"<p>Drittdienstleister und Unterauftragsverarbeiter F\u00fcr unsere Cloud-basierten und KI-gest\u00fctzten Funktionen arbeiten wir mit sorgf\u00e4ltig ausgew\u00e4hlten Drittanbietern zusammen. Diese Dienstleister erhalten nur die Daten, die f\u00fcr die Erf\u00fcllung der gew\u00fcnschten Aufgabe notwendig sind. Mit allen eingesetzten Dienstleistern wurden die erforderlichen vertraglichen Vereinbarungen geschlossen, insbesondere Auftragsverarbeitungsvertr\u00e4ge gem\u00e4\u00df Art. 28 DSGVO. Sofern eine Verarbeitung personenbezogener Daten in einem Drittland [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":121894,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"custom-page-header.php","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-124671","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Drittdienstleister und Unterauftragsverarbeiter | MAXQDA<\/title>\n<meta name=\"description\" content=\"Drittdienstleister und Unterauftragsverarbeiter | MAXQDA - Die beste Wahl f\u00fcr Ihre Qualitative &amp; Mixed-Methods-Analyse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maxqda.com\/de\/drittdienstleister\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drittdienstleister und Unterauftragsverarbeiter\" \/>\n<meta property=\"og:description\" content=\"Drittdienstleister und Unterauftragsverarbeiter F\u00fcr unsere Cloud-basierten und KI-gest\u00fctzten Funktionen arbeiten wir mit sorgf\u00e4ltig ausgew\u00e4hlten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maxqda.com\/de\/drittdienstleister\" \/>\n<meta property=\"og:site_name\" content=\"MAXQDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MAXQDA\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T15:50:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Die-1-Software-fuer-qualitative-und-Mixed-Methods-Datenanalyse.png?_t=1771861847\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VerbiSoftware\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/drittdienstleister\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/drittdienstleister\",\"name\":\"Drittdienstleister und Unterauftragsverarbeiter | MAXQDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/drittdienstleister#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/drittdienstleister#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo-MQ.jpg\",\"datePublished\":\"2024-05-07T10:47:31+00:00\",\"dateModified\":\"2026-02-23T15:50:42+00:00\",\"description\":\"Drittdienstleister und Unterauftragsverarbeiter | MAXQDA - Die beste Wahl f\u00fcr Ihre Qualitative & Mixed-Methods-Analyse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/drittdienstleister#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.maxqda.com\\\/de\\\/drittdienstleister\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/drittdienstleister#primaryimage\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo-MQ.jpg\",\"contentUrl\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo-MQ.jpg\",\"width\":825,\"height\":825,\"caption\":\"MAXQDA Logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/drittdienstleister#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drittdienstleister und Unterauftragsverarbeiter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/\",\"name\":\"MAXQDA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#organization\",\"name\":\"MAXQDA\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo.png\",\"width\":\"1000\",\"height\":\"200\",\"caption\":\"MAXQDA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MAXQDA\\\/\",\"https:\\\/\\\/x.com\\\/VerbiSoftware\",\"https:\\\/\\\/www.instagram.com\\\/maxqda\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/MAXQDA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Drittdienstleister und Unterauftragsverarbeiter | MAXQDA","description":"Drittdienstleister und Unterauftragsverarbeiter | MAXQDA - Die beste Wahl f\u00fcr Ihre Qualitative & Mixed-Methods-Analyse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maxqda.com\/de\/drittdienstleister","og_locale":"de_DE","og_type":"article","og_title":"Drittdienstleister und Unterauftragsverarbeiter","og_description":"Drittdienstleister und Unterauftragsverarbeiter F\u00fcr unsere Cloud-basierten und KI-gest\u00fctzten Funktionen arbeiten wir mit sorgf\u00e4ltig ausgew\u00e4hlten","og_url":"https:\/\/www.maxqda.com\/de\/drittdienstleister","og_site_name":"MAXQDA","article_publisher":"https:\/\/www.facebook.com\/MAXQDA\/","article_modified_time":"2026-02-23T15:50:42+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Die-1-Software-fuer-qualitative-und-Mixed-Methods-Datenanalyse.png?_t=1771861847","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@VerbiSoftware","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.maxqda.com\/de\/drittdienstleister","url":"https:\/\/www.maxqda.com\/de\/drittdienstleister","name":"Drittdienstleister und Unterauftragsverarbeiter | MAXQDA","isPartOf":{"@id":"https:\/\/www.maxqda.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maxqda.com\/de\/drittdienstleister#primaryimage"},"image":{"@id":"https:\/\/www.maxqda.com\/de\/drittdienstleister#primaryimage"},"thumbnailUrl":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo-MQ.jpg","datePublished":"2024-05-07T10:47:31+00:00","dateModified":"2026-02-23T15:50:42+00:00","description":"Drittdienstleister und Unterauftragsverarbeiter | MAXQDA - Die beste Wahl f\u00fcr Ihre Qualitative & Mixed-Methods-Analyse","breadcrumb":{"@id":"https:\/\/www.maxqda.com\/de\/drittdienstleister#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maxqda.com\/de\/drittdienstleister"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.maxqda.com\/de\/drittdienstleister#primaryimage","url":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo-MQ.jpg","contentUrl":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo-MQ.jpg","width":825,"height":825,"caption":"MAXQDA Logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.maxqda.com\/de\/drittdienstleister#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.maxqda.com\/de\/"},{"@type":"ListItem","position":2,"name":"Drittdienstleister und Unterauftragsverarbeiter"}]},{"@type":"WebSite","@id":"https:\/\/www.maxqda.com\/de\/#website","url":"https:\/\/www.maxqda.com\/de\/","name":"MAXQDA","description":"","publisher":{"@id":"https:\/\/www.maxqda.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maxqda.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.maxqda.com\/de\/#organization","name":"MAXQDA","url":"https:\/\/www.maxqda.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.maxqda.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo.png","contentUrl":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo.png","width":"1000","height":"200","caption":"MAXQDA"},"image":{"@id":"https:\/\/www.maxqda.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MAXQDA\/","https:\/\/x.com\/VerbiSoftware","https:\/\/www.instagram.com\/maxqda\/","https:\/\/www.youtube.com\/user\/MAXQDA"]}]}},"_links":{"self":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/pages\/124671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/comments?post=124671"}],"version-history":[{"count":4,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/pages\/124671\/revisions"}],"predecessor-version":[{"id":132461,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/pages\/124671\/revisions\/132461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/media\/121894"}],"wp:attachment":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/media?parent=124671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}