{"id":120671,"date":"2023-09-19T12:05:14","date_gmt":"2023-09-19T11:05:14","guid":{"rendered":"https:\/\/www.maxqda.com\/de\/?page_id=120671"},"modified":"2023-12-05T15:47:49","modified_gmt":"2023-12-05T14:47:49","slug":"quantitative-textanalyse","status":"publish","type":"page","link":"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse","title":{"rendered":"Quantitative Textanalyse"},"content":{"rendered":"<div class=\"row\">\r\n\t\r\n\t<div class=\"large-12 row-margin-80 large-centered\">\r\n\t\t\r\n\t\t<div class=\"large-10 small-12 columns large-centered\">\r\n\t\t\t<h2 class=\"text-center\">Die beste Wahl f\u00fcr quantitative Textanalysen<\/h2>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"large-10 small-12 large-centered columns margin-top-80 text-center\">\r\n\t\t\t<p style=\"font-size:1.3rem; line-height:2.1rem; text-align: justify;\"><b>MAXQDA<\/b> beinhaltet den Tab MAXDictio. MAXDictio erm\u00f6glicht die Durchf\u00fchrung zahlreicher Verfahren zur <b>quantitativen Textanalyse<\/b>, insbesondere innerhalb von qualitativ orientierten Projekten. Mit enthalten sind Tools zur <b>visuellen Textexploration<\/b>, zur Durchf\u00fchrung von <b>Wortschatzanalysen<\/b> und <b>Inhaltsanalysen<\/b>, sowie zur Operationalisierung von Diktion\u00e4ren, mit denen Gruppen von selbst definierten W\u00f6rtern angelegt und ausgewertet werden k\u00f6nnen.<\/p>\r\n\t\t<\/div>\r\n\r\n\r\n\t\t<div class=\"row row-order\" data-equalizer data-equalize-on=\"large\">\r\n\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-bottom\" data-equalizer-watch>\r\n\t\t\t\t<h3>Visuelle Text-Exploration<\/h3>\r\n\t\t\t\t<p style=\"font-size:1rem; text-align: justify;\">Ganz gleich ob Sie nun einzelne Dokumente oder ein ganzes B\u00fccherregal analysieren wollen: <b>MAXDictio gew\u00e4hrt Ihnen Einblick in Inhalt und Struktur Ihrer Texte, ohne auch nur einen einzigen Satz im Voraus lesen und codieren zu m\u00fcssen<\/b>. Der <b>Word Tree<\/b> visualisiert zum Beispiel alle Wortkombinationen die zu einem (frei definierbaren) Wort hin- beziehungsweise davon wegf\u00fchren, inklusive einer <b>detaillierten Ausgabe aller H\u00e4ufigkeiten<\/b>. Durch die Interaktivit\u00e4t k\u00f6nnen Sie Strukturmerkmale und Zusammenh\u00e4nge auf einen Blick ausmachen \u2013 eine gleicherma\u00dfen komfortable und h\u00f6chst effiziente M\u00f6glichkeit zur Textexploration und -analyse.<\/p>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-top text-center\" data-equalizer-watch>\r\n\t\t\t\t<div class=\"img-bg img-bg-2\" style=\"padding: 80px;\">\r\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/Dictio_WordTree.png\"  class=\"aligncenter\" alt=\"MAXDictio Word Tree\" title=\"MAXDictio Word Tree\"\/>\r\n\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\r\n\r\n\t\t<div class=\"row row-order\" data-equalizer data-equalize-on=\"large\">\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-top\" data-equalizer-watch>\r\n\t\t\t\t<div class=\"img-bg img-bg-3\"  style=\"padding: 80px;\"\/>\r\n\t\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXDictio_Keyword-in-context.png\"  class=\"aligncenter\" alt=\"MAXDictio - Keyword-in-Context\" title=\"MAXDictio - Keyword-in-Context\"\/>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-bottom left center-vertical\" data-equalizer-watch>\r\n\t\t\t\t<div>\r\n\t\t\t\t\t<h3>Inhaltsanalysen: Von einzelnen W\u00f6rtern\u2026<\/h3>\r\n\t\t\t\t\t<p style=\"font-size:1rem; text-align: justify;\">MAXDictio unterst\u00fctzt Sie bei der Umsetzung von <b>Inhaltsanalysen unterschiedlichster methodischer Vorgehensweisen und methodologischer Hintergr\u00fcnde<\/b>. Vielf\u00e4ltige M\u00f6glichkeiten zur Zergliederung, (Re-)Kontextualisierung und Visualisierung schaffen einen \u00dcberblick \u00fcber das Material und er\u00f6ffnen Freir\u00e4ume f\u00fcr die Analyse. Um mehr \u00fcber die Verwendung und Bedeutung einzelner W\u00f6rter in Ihrem Material zu erfahren, nutzen Sie die <b>\u201eKeyword-in-Context\u201c-Funktion<\/b> um alle Fundstellen eines Wortes, inklusive des jeweiligen Kontexts, in einer \u00fcbersichtlichen und interaktiven Tabelle angezeigt zu bekommen.<\/p>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t<\/div>\t\r\n\t\t\t\r\n\t\t<div class=\"row row-order\" data-equalizer data-equalize-on=\"large\">\r\n\t\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-bottom center-vertical\" data-equalizer-watch>\r\n\t\t\t\t<div>\r\n\t\t\t\t\t<h3>\u2026 zu ganzen Wortkombinationen<\/h3>\r\n\t\t\t\t\t<p style=\"font-size:1rem; text-align: justify;\">Lassen Sie sich die <b>H\u00e4ufigkeiten, R\u00e4nge und Verteilung von Wortkombinationen<\/b> anzeigen. Sie k\u00f6nnen die Ergebnisse Ihrem eigenen Erkenntnisinteresse entsprechend filtern, und sich detaillierte Ergebnisse f\u00fcr codierte Segmente, einzelne Dokumente oder Dokumentgruppen beziehungsweise -sets anzeigen lassen. Die erweiterten Optionen erlauben die <b>Lemmatisierung<\/b> (Zusammenfassung von W\u00f6rtern nach gemeinsamem Wortstamm), die Nutzung von <b>Stopplisten<\/b>, das <b>automatische Codieren<\/b> der Ergebnisse und vieles mehr. <\/p>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-top left\" data-equalizer-watch>\r\n\t\t\t\t<div class=\"img-bg img-bg-3\"  style=\"padding: 80px;\">\r\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXDictio_WordCombinations.png\"  class=\"aligncenter\" alt=\"MAXDictio - Wortkombinationen\" title=\"MAXDictio - Wortkombinationen\"\/>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t<\/div>\t\r\n\t\t\r\n\t\t<div class=\"row row-order\" data-equalizer data-equalize-on=\"large\">\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-top\" data-equalizer-watch>\r\n\t\t\t\t<div class=\"img-bg img-bg-1\"  style=\"padding: 80px;\">\r\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXDictio_WordFrequencies.png\"  class=\"aligncenter\" alt=\"MAXDictio - Worth\u00e4ufigkeiten\" title=\"MAXDictio - Worth\u00e4ufigkeiten\"\/>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-bottom left center-vertical\" data-equalizer-watch>\r\n\t\t\t\t<div>\r\n\t\t\t\t\t<h3>Wortschatzanalyse<\/h3>\r\n\t\t\t\t\t<p style=\"font-size:1rem; text-align: justify;\">Benutzen Sie MAXDictio, um sich die H\u00e4ufigkeiten, R\u00e4nge und Verteilung von W\u00f6rtern in Ihrem Material anzeigen zu lassen. Auch hier k\u00f6nnen Sie Ihr Material aufgliedern um sich detaillierte Informationen zu einzelnen Dokumenten, Codes oder Dokumentgruppen beziehungsweise -sets anzeigen zu lassen. Wie bei allen Ergebnisfenstern in MAXDictio k\u00f6nnen Sie sich Ihre <b>Ergebnisse als Excel- oder HTML-Datei<\/b> exportieren lassen.      <\/p>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t<\/div>\t\r\n\t\t\r\n\t\t<div class=\"row row-order\" data-equalizer data-equalize-on=\"large\">\r\n\t\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-bottom center-vertical\" data-equalizer-watch>\r\n\t\t\t\t<div>\r\n\t\t\t\t\t<h3>Diktion\u00e4rsbasierte Analysen: Definieren Sie Kategorien\u2026<\/h3>\r\n\t\t\t\t\t<p style=\"font-size:1rem; text-align: justify;\">Mit dem <b>Diktion\u00e4r<\/b> k\u00f6nnen Sie <b>Kategorien von Suchw\u00f6rtern definieren<\/b>, deren Vorkommen Sie anschlie\u00dfend erheben und vergleichen k\u00f6nnen. Ob Sie diese W\u00f6rter nun eintippen, per Drag &#038; Drop aus einem Ergebnisfenster transferieren, von einer Datei importieren oder aus Codes generieren lassen: Es bieten sich anschlie\u00dfend eine Menge M\u00f6glichkeiten, Ihr Diktion\u00e4r zu verwenden. Sie k\u00f6nnen das <b>Vorkommen einzelner W\u00f6rter<\/b> miteinander vergleichen\u2026 <\/p>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-top left\" data-equalizer-watch>\r\n\t\t\t\t<div class=\"img-bg img-bg-2\" style=\"padding: 80px;\">\r\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXDictio_Categories.png\"  class=\"aligncenter\" \/>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t<div class=\"row row-order\" data-equalizer data-equalize-on=\"large\">\r\n\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-top\" data-equalizer-watch>\r\n\t\t\t\t<div class=\"img-bg img-bg-3\"  style=\"padding: 80px;\">\r\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXDictio_DictionaryBasedAnalysis.png\"  class=\"aligncenter\" \/>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-bottom left center-vertical\" data-equalizer-watch>\r\n\t\t\t\t<div>\r\n\t\t\t\t\t<h3>\u2026 und entdecken Sie deren N\u00fctzlichkeit<\/h3>\r\n\t\t\t\t\t<p style=\"font-size:1rem; text-align: justify;\">\u2026 oder das <b>Vorkommen ganzer Kategorien<\/b> untersuchen. Sie k\u00f6nnen Ihre Ergebnisse auch mithilfe des <b>Kategorien-Matrix-Browser<\/b> visualisieren. Sobald Sie Ihre Analyse auf einer anderen Ebene fortf\u00fchren wollen, lassen Sie sich Ihr Diktion\u00e4r mit allen Kategorien und Suchw\u00f6rtern <b>automatisch codieren<\/b> \u2013 oder operationalisieren Sie die H\u00e4ufigkeiten in Form von Dokumentvariablen. In Verbindung mit unseren <b>Mixed-Methods-Funktionen<\/b> sind Ihrem Erfindungsreichtum keine Grenzen gesetzt.<\/p>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\t\r\n\t\t\r\n\t\t<div class=\"row row-order\" data-equalizer data-equalize-on=\"large\">\r\n\t\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-bottom center-vertical\" data-equalizer-watch>\r\n\t\t\t\t<div>\r\n\t\t\t\t\t<h3>Mehr Funktionen<\/h3>\r\n\t\t\t\t\t<p style=\"font-size:1rem; text-align: justify;\">MAXDictio unterst\u00fctzt die Analyse von <b>japanischen Texten<\/b>, erm\u00f6glicht die komfortable Verwaltung von mehreren <b>Stopp- und Go-Listen<\/b> und kann auf Knopfdruck <b>Wortwolken<\/b> f\u00fcr beliebige Teile Ihres Materials erstellen. Mit unseren <b>interaktiven Ergebnisfenstern<\/b> sind Sie immer nur einen Klick von der originalen Fundstelle entfernt. Definieren Sie exakt, wieviel W\u00f6rter, S\u00e4tze oder Abs\u00e4tze einer Fundstelle Sie <b>automatisch (mit)codieren<\/b> lassen m\u00f6chten, und exportieren Sie Ihre Ergebnisse als Excel- oder HTML-Datei.   <\/p>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"large-6 small-12 columns mobile-top left\" data-equalizer-watch>\r\n\t\t\t\t<div class=\"img-bg img-bg-3\"  style=\"padding: 80px;\">\r\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXDictio_Features.png\"  class=\"aligncenter\" \/>\r\n\t\t\t\t<\/div>\t\r\n\t\t\t<\/div>\t\r\n\t\t<\/div>\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t<div class=\"large-12 small-12 text-center margin-top-40\">\r\n\t\t\t<a class=\"button\" title=\"Go back to the MAXQDA Product Overview\" href=\"https:\/\/www.maxqda.com\/de\/produkte\">Zur\u00fcck zur MAXQDA Produkt\u00fcbersicht<\/a>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"large-12 small-12 text-center margin-top-80\">\r\n\t\t\t<h2>Mehr erfahren:<\/h2>\r\n\t\t<\/div>\r\n\t\t\r\n\r\n\t\t<div class=\"row bottom-links\" data-equalizer>\r\n\t\t\t<div class=\"box-25 shadow-box\" data-equalizer-watch>\r\n\t\t\t\t<a href=\"https:\/\/www.maxqda.com\/blogpost\/how-to-use-maxqda-for-word-combination-analysis\">\r\n\t\t\t\t\t<div>\r\n\t\t\t\t\t\t<div class=\"bottom-links-img\">\r\n\t\t\t\t\t\t\t\t\t<svg version=\"1.1\" id=\"Ebene_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n\t\t\t\t\t\t\t\t\t\t viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 64 64;\" xml:space=\"preserve\">\r\n\t\t\t\t\t\t\t\t\t<g id=\"Blog\">\r\n\t\t\t\t\t\t\t\t\t\t<g>\r\n\t\t\t\t\t\t\t\t\t\t\t<path style=\"fill:#DD4830;\" d=\"M59.996,12C60.55,12,61,12.45,61,13.004v37.992C61,51.55,60.55,52,59.996,52H4.004\r\n\t\t\t\t\t\t\t\t\t\t\t\tC3.45,52,3,51.55,3,50.996V13.004C3,12.45,3.45,12,4.004,12H59.996 M59.996,10H4.004C2.345,10,1,11.345,1,13.004v37.992\r\n\t\t\t\t\t\t\t\t\t\t\t\tC1,52.655,2.345,54,4.004,54h55.992C61.655,54,63,52.655,63,50.996V13.004C63,11.345,61.655,10,59.996,10L59.996,10z\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<\/g>\r\n\t\t\t\t\t\t\t\t\t\t<path style=\"fill:#DD4830;\" d=\"M17.5,18C12.253,18,8,22.253,8,27.5s4.253,9.5,9.5,9.5s9.5-4.253,9.5-9.5S22.747,18,17.5,18z\r\n\t\t\t\t\t\t\t\t\t\t\t M17.5,20c4.007,0,7.28,3.161,7.481,7.118l-1.928,1.829L20,25l-4,4l-1.895-2l-3.773,2.708C10.117,29.01,10,28.268,10,27.5\r\n\t\t\t\t\t\t\t\t\t\t\tC10,23.365,13.365,20,17.5,20z\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<circle style=\"fill:#F4803A;\" cx=\"15\" cy=\"24\" r=\"2\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#DD4830;stroke-width:2;stroke-miterlimit:10;\" x1=\"32\" y1=\"19\" x2=\"56\" y2=\"19\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"32\" y1=\"23\" x2=\"56\" y2=\"23\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"32\" y1=\"27\" x2=\"56\" y2=\"27\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"32\" y1=\"31\" x2=\"56\" y2=\"31\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"32\" y1=\"35\" x2=\"48\" y2=\"35\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"32\" y1=\"39\" x2=\"51\" y2=\"39\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"32\" y1=\"43\" x2=\"52\" y2=\"43\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"8.218\" y1=\"42\" x2=\"23.782\" y2=\"42\"\/>\r\n\t\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"8.218\" y1=\"46\" x2=\"18.218\" y2=\"46\"\/>\r\n\t\t\t\t\t\t\t\t\t<\/g>\r\n\t\t\t\t\t\t\t\t\t<\/svg>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"bottom-links-text\">\t\t\r\n\t\t\t\t\t\t\t<p>Quantitative Textanalyse<\/p>\r\n\t\t\t\t\t\t\t<b>Blog<\/b>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t<div class=\"box-25 shadow-box\" data-equalizer-watch>\r\n\t\t\t\t<a href=\"https:\/\/www.maxqda.com\/de\/hilfe\/import-dictio\/was-leistet-maxdictio\">\r\n\t\t\t\t\t<div>\r\n\t\t\t\t\t\t<div class=\"bottom-links-img\">\r\n\t\t\t\t\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n\t viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 64 64;\" xml:space=\"preserve\">\r\n\t\t\t\t\t\t\t\t<g id=\"Manual\">\r\n\t\t\t\t\t\t\t\t\t<path style=\"fill:none;stroke:#DD4830;stroke-width:2;stroke-miterlimit:10;\" d=\"M50.12,61H14.88C13.29,61,12,59.71,12,58.12V5.88\r\n\t\t\t\t\t\t\t\t\t\tC12,4.29,13.29,3,14.88,3H50.12C51.71,3,53,4.29,53,5.88V58.12C53,59.71,51.71,61,50.12,61z\"\/>\r\n\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#DD4830;stroke-width:2;stroke-miterlimit:10;\" x1=\"17\" y1=\"11\" x2=\"48\" y2=\"11\"\/>\r\n\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"17\" y1=\"15\" x2=\"48\" y2=\"15\"\/>\r\n\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"17\" y1=\"19\" x2=\"48\" y2=\"19\"\/>\r\n\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"17\" y1=\"23\" x2=\"48\" y2=\"23\"\/>\r\n\t\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"17\" y1=\"27\" x2=\"39\" y2=\"27\"\/>\r\n\t\t\t\t\t\t\t\t\t<polygon style=\"fill:none;stroke:#DD4830;stroke-width:2;stroke-miterlimit:10;\" points=\"17.991,34.018 46.97,34.018 47,53 \r\n\t\t\t\t\t\t\t\t\t\t18.01,53 \t\"\/>\r\n\t\t\t\t\t\t\t\t\t<polyline style=\"fill:none;stroke:#DD4830;stroke-width:2;stroke-miterlimit:10;\" points=\"18,49 23,44 27,48 32,41 37,48 39,45 \r\n\t\t\t\t\t\t\t\t\t\t41.917,48.083 47,41.167 \t\"\/>\r\n\t\t\t\t\t\t\t\t<\/g>\r\n\t\t\t\t\t\t\t<\/svg>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"bottom-links-text\">\t\r\n\t\t\t\t\t\t\t<p>Quantitative Textanalyse<\/p>\r\n\t\t\t\t\t\t\t<b>Manual<\/b>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t<div class=\"box-25 shadow-box\" data-equalizer-watch>\r\n\t\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=pNMRPIcKnfY\">\r\n\t\t\t\t\t<div>\r\n\t\t\t\t\t\t<div class=\"bottom-links-img\">\r\n\t\t\t\t\t\t\t<svg version=\"1.1\" id=\"Ebene_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n\t\t\t\t\t\t\t\t\t\t viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 64 64;\" xml:space=\"preserve\">\r\n\t\t\t\t\t\t\t\t\t\t <g id=\"Ebene_3\">\r\n\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" x1=\"58.049\" y1=\"45.481\" x2=\"58.049\" y2=\"22.071\"\/>\r\n\t\t\t\t\t\t\t\t<polygon style=\"fill:none;stroke:#DD4830;stroke-width:2;stroke-miterlimit:10;\" points=\"2.049,20.519 30.937,10.463 \r\n\t\t\t\t\t\t\t\t\t61.993,20.537 31.049,32.575 \t\"\/>\r\n\t\t\t\t\t\t\t\t<polyline style=\"fill:none;stroke:#DD4830;stroke-width:2;stroke-miterlimit:10;\" points=\"12,25 12,40 31,49 52,40 52,25 \t\"\/>\r\n\t\t\t\t\t\t\t\t<circle style=\"fill:#F4803A;\" cx=\"58\" cy=\"49\" r=\"4\"\/>\r\n\t\t\t\t\t\t\t<\/g>\r\n\t\t\t\t\t\t\t<\/svg>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"bottom-links-text\">\t\t\r\n\t\t\t\t\t\t\t<p>Quantitative Textanalyse<\/p>\r\n\t\t\t\t\t\t\t<b>Tutorials<\/b>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t<div class=\"box-25 shadow-box\" data-equalizer-watch>\r\n\t\t\t\t<a href=\"https:\/\/www.maxqda.com\/training\/live-training\">\r\n\t\t\t\t\t<div>\r\n\t\t\t\t\t\t<div class=\"bottom-links-img\">\r\n\t\t\t\t\t\t\t<svg version=\"1.1\" id=\"Ebene_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n\t\t\t\t\t\t\t\t\t\t viewBox=\"0 0 64 64\" style=\"enable-background:new 0 0 64 64;\" xml:space=\"preserve\">\r\n\t\t\t\t\t\t\t\t<g id=\"webinar\">\r\n\t\t\t\t\t\t\t\t<path style=\"fill:none;stroke:#DD4830;stroke-width:2;stroke-miterlimit:10;\" d=\"M3,53.5c0-6.627,5.373-12,12-12s12,5.373,12,12\"\/>\r\n\t\t\t\t\t\t\t\t<circle style=\"fill:none;stroke:#DD4830;stroke-width:2;stroke-miterlimit:10;\" cx=\"15\" cy=\"31.5\" r=\"6\"\/>\r\n\t\t\t\t\t\t\t\t<line style=\"fill:none;stroke:#DD4830;stroke-width:2;stroke-miterlimit:10;\" x1=\"26\" y1=\"41.5\" x2=\"40\" y2=\"27.5\"\/>\r\n\t\t\t\t\t\t\t\t<path style=\"fill:none;stroke:#F4803A;stroke-width:2;stroke-miterlimit:10;\" d=\"M29,34L29,34c-1.105,0-2-0.895-2-2V13\r\n\t\t\t\t\t\t\t\t\tc0-1.105,0.895-2,2-2h30c1.105,0,2,0.895,2,2v19c0,1.105-0.895,2-2,2H38.167\"\/>\r\n\t\t\t\t\t\t\t<\/g>\r\n\t\t\t\t\t\t\t<\/svg>\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"bottom-links-text\">\t\t\r\n\t\t\t\t\t\t\t<p>Quantitative Textanalyse<\/p>\r\n\t\t\t\t\t\t\t<b>Webinars &#038; Workshops<\/b>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\r\n\t\t<\/div>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>Die beste Wahl f\u00fcr quantitative Textanalysen MAXQDA beinhaltet den Tab MAXDictio. MAXDictio erm\u00f6glicht die Durchf\u00fchrung zahlreicher Verfahren zur quantitativen Textanalyse, insbesondere innerhalb von qualitativ orientierten Projekten. Mit enthalten sind Tools zur visuellen Textexploration, zur Durchf\u00fchrung von Wortschatzanalysen und Inhaltsanalysen, sowie zur Operationalisierung von Diktion\u00e4ren, mit denen Gruppen von selbst definierten W\u00f6rtern angelegt und ausgewertet werden [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":121894,"parent":0,"menu_order":13,"comment_status":"closed","ping_status":"closed","template":"custom-page-header.php","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-120671","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quantitative Textanalyse | MAXQDA<\/title>\n<meta name=\"description\" content=\"Quantitative Textanalyse | MAXQDA - Die beste Wahl f\u00fcr Ihre Qualitative &amp; Mixed-Methods-Analyse\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quantitative Textanalyse\" \/>\n<meta property=\"og:description\" content=\"Die beste Wahl f\u00fcr quantitative Textanalysen MAXQDA beinhaltet den Tab MAXDictio. MAXDictio erm\u00f6glicht die Durchf\u00fchrung zahlreicher Verfahren zur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse\" \/>\n<meta property=\"og:site_name\" content=\"MAXQDA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MAXQDA\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-05T14:47:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo-MQ.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"825\" \/>\n\t<meta property=\"og:image:height\" content=\"825\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VerbiSoftware\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/quantitative-textanalyse\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/quantitative-textanalyse\",\"name\":\"Quantitative Textanalyse | MAXQDA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/quantitative-textanalyse#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/quantitative-textanalyse#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo-MQ.jpg\",\"datePublished\":\"2023-09-19T11:05:14+00:00\",\"dateModified\":\"2023-12-05T14:47:49+00:00\",\"description\":\"Quantitative Textanalyse | MAXQDA - Die beste Wahl f\u00fcr Ihre Qualitative & Mixed-Methods-Analyse\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/quantitative-textanalyse#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.maxqda.com\\\/de\\\/quantitative-textanalyse\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/quantitative-textanalyse#primaryimage\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo-MQ.jpg\",\"contentUrl\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo-MQ.jpg\",\"width\":825,\"height\":825,\"caption\":\"MAXQDA Logo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/quantitative-textanalyse#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quantitative Textanalyse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/\",\"name\":\"MAXQDA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#organization\",\"name\":\"MAXQDA\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/wp\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/MAXQDA-Logo.png\",\"width\":\"1000\",\"height\":\"200\",\"caption\":\"MAXQDA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.maxqda.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MAXQDA\\\/\",\"https:\\\/\\\/x.com\\\/VerbiSoftware\",\"https:\\\/\\\/www.instagram.com\\\/maxqda\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/MAXQDA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quantitative Textanalyse | MAXQDA","description":"Quantitative Textanalyse | MAXQDA - Die beste Wahl f\u00fcr Ihre Qualitative & Mixed-Methods-Analyse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse","og_locale":"de_DE","og_type":"article","og_title":"Quantitative Textanalyse","og_description":"Die beste Wahl f\u00fcr quantitative Textanalysen MAXQDA beinhaltet den Tab MAXDictio. MAXDictio erm\u00f6glicht die Durchf\u00fchrung zahlreicher Verfahren zur","og_url":"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse","og_site_name":"MAXQDA","article_publisher":"https:\/\/www.facebook.com\/MAXQDA\/","article_modified_time":"2023-12-05T14:47:49+00:00","og_image":[{"width":825,"height":825,"url":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo-MQ.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@VerbiSoftware","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse","url":"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse","name":"Quantitative Textanalyse | MAXQDA","isPartOf":{"@id":"https:\/\/www.maxqda.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse#primaryimage"},"image":{"@id":"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse#primaryimage"},"thumbnailUrl":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo-MQ.jpg","datePublished":"2023-09-19T11:05:14+00:00","dateModified":"2023-12-05T14:47:49+00:00","description":"Quantitative Textanalyse | MAXQDA - Die beste Wahl f\u00fcr Ihre Qualitative & Mixed-Methods-Analyse","breadcrumb":{"@id":"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maxqda.com\/de\/quantitative-textanalyse"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse#primaryimage","url":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo-MQ.jpg","contentUrl":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo-MQ.jpg","width":825,"height":825,"caption":"MAXQDA Logo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.maxqda.com\/de\/quantitative-textanalyse#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.maxqda.com\/de\/"},{"@type":"ListItem","position":2,"name":"Quantitative Textanalyse"}]},{"@type":"WebSite","@id":"https:\/\/www.maxqda.com\/de\/#website","url":"https:\/\/www.maxqda.com\/de\/","name":"MAXQDA","description":"","publisher":{"@id":"https:\/\/www.maxqda.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maxqda.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.maxqda.com\/de\/#organization","name":"MAXQDA","url":"https:\/\/www.maxqda.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.maxqda.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo.png","contentUrl":"https:\/\/www.maxqda.com\/de\/wp\/wp-content\/uploads\/sites\/1\/MAXQDA-Logo.png","width":"1000","height":"200","caption":"MAXQDA"},"image":{"@id":"https:\/\/www.maxqda.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MAXQDA\/","https:\/\/x.com\/VerbiSoftware","https:\/\/www.instagram.com\/maxqda\/","https:\/\/www.youtube.com\/user\/MAXQDA"]}]}},"_links":{"self":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/pages\/120671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/comments?post=120671"}],"version-history":[{"count":0,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/pages\/120671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/media\/121894"}],"wp:attachment":[{"href":"https:\/\/www.maxqda.com\/de\/wp-json\/wp\/v2\/media?parent=120671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}